{"id":64,"date":"2023-01-03T23:21:44","date_gmt":"2023-01-03T23:21:44","guid":{"rendered":"https:\/\/portosma.com.br\/?page_id=64"},"modified":"2026-06-19T14:14:13","modified_gmt":"2026-06-19T14:14:13","slug":"soamar","status":"publish","type":"page","link":"https:\/\/portosma.com.br\/index.php\/soamar\/","title":{"rendered":"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o"},"content":{"rendered":"\r\n<h1><span style=\"color: #000000;\">Soamar Maranh\u00e3o completa 47 anos de hist\u00f3ria, dedica\u00e7\u00e3o, e amor \u00e0 Marinha<\/span><\/h1>\r\n<p><span style=\"color: #800000;\"><strong>Falar da hist\u00f3ria da Soamar \u2013 Sociedade Amigos da Marinha do Estados do Maranh\u00e3o, sem lembrar dos seus baluartes, seus pioneiros, de homens que, alguns vindos de bem longe como Herc\u00edlio Luz Sim\u00f5es e M\u00e1rio Flexa, adotaram o Estado como \u201cp\u00e1tria amada\u201d e a Marinha como amiga. Foi assim, com essa reciprocidade que s\u00f3 as verdadeiras amizades s\u00e3o capazes de produzir, que nasceu esta entidade cuja miss\u00e3o maior, \u00e9 \u201clinkar\u201d a sociedade civil maranhense com os conceitos nobres e \u00e9ticos que que a Marinha tem, e que aceitou, de bom grado, e de m\u00e9rito, acolher, junto aos seus pares, esses cidad\u00e3os conhecidos em todo o pa\u00eds pelo nome de soamarinos. Hoje, 47 anos depois, a Soamar do Maranh\u00e3o tem como diretor presidente S\u00edlvio L\u00facio de Oliveira Aguiar e, a Soamar Brasil \u2013 que j\u00e1 teve entre os seus mandat\u00e1rios \u201cmaranhenses\u201d como Herc\u00edlio Luz Sim\u00f5es e Orson Ant\u00f4nio Feres Moraes Rego \u2013 \u00e9 comandada pelo cearense Jorge Eduardo Pessoa Arag\u00e3o.<\/strong><\/span><\/p>\r\n<figure id=\"attachment_31287\" aria-describedby=\"caption-attachment-31287\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-31287 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg\" alt=\"\" width=\"900\" height=\"494\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04-300x165.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04-768x422.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-31287\" class=\"wp-caption-text\"><span style=\"color: #800000;\"><em><strong>Imponente sede social da Soamar do Maranh\u00e3o, em S\u00e3o Lu\u00eds, na \u00e1rea do Jenipaperio.<\/strong><\/em><\/span><\/figcaption><\/figure>\r\n<h4><strong>Palavra do Presidente pelos 47 Anos da Soamar Maranh\u00e3o<\/strong><\/h4>\r\n<h4><strong><span style=\"color: #000080;\">18 de junho de 1979 \u2014 18 de junho de 2026<\/span><\/strong><\/h4>\r\n<p><em><img decoding=\"async\" class=\"alignleft wp-image-31284\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-06-235x300.jpg\" alt=\"\" width=\"200\" height=\"255\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-06-235x300.jpg 235w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-06.jpg 250w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/em><span style=\"color: #000000;\">Caros Soamarinos e Soamarinas, autoridades civis e militares, amigos da Marinha do Maranh\u00e3o. <\/span><span style=\"color: #000000;\">\u00c9 com profunda satisfa\u00e7\u00e3o que celebramos hoje, 18 de junho, os 47 anos de funda\u00e7\u00e3o da Sociedade Amigos da Marinha do Estado do Maranh\u00e3o \u2013 Soamar\/MA. Quase cinco d\u00e9cadas de hist\u00f3ria que merecem ser relembradas e honradas.<\/span><\/p>\r\n<p><strong><em>As Origens:<\/em><\/strong><\/p>\r\n<p><span style=\"color: #000000;\"><em>Nossa entidade nasceu em 1979, em S\u00e3o Lu\u00eds, do idealismo de um grupo de moradores da capital maranhense, agraciados como os primeiros Amigos da Marinha do estado. Reunidos em assembleia geral em uma das salas do por\u00e3o da Capitania dos Portos, esses s\u00f3cios fundadores deram \u00e0 luz a Soamar\/MA, sob a inspira\u00e7\u00e3o do ent\u00e3o Ministro da Marinha e Patrono da SOAMAR, Almirante de Esquadra Maximiano Eduardo da Silva Fonseca. Seu primeiro presidente foi o escritor e jornalista M\u00e1rio Martins Meireles, que abriu o caminho para todos que viriam depois.<\/em><\/span><\/p>\r\n<p><strong><em>Uma Trajet\u00f3ria de Lideran\u00e7as:<\/em><\/strong><\/p>\r\n<p><span style=\"color: #000000;\">Ao longo destes 47 anos, catorze diretorias diferentes conduziram os destinos da Soamar\/MA, cada uma deixando sua marca particular. Nos \u00faltimos quinze anos, esse legado foi constru\u00eddo por:<\/span><\/p>\r\n<ul>\r\n<li><span style=\"color: #000000;\"><em> Orson Ant\u00f4nio Feres Moraes R\u00eago (2011\u20132015 e, em terceiro mandato, 2017\u20132019), que conduziu a entidade em parceria estreita e prof\u00edcua com a Marinha do Brasil;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Ricardo Miccuci dos Santos (2015\u20132017), que deu continuidade ao trabalho de fortalecimento institucional;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Orson A. Feres Moraes Rego (2017-2019), per\u00edodo em que tamb\u00e9m chegou a acumular a presid\u00eancia nacional da Soamar Brasil; Jobert Jos\u00e9 Salgado Filho (2019\u20132021), respons\u00e1vel por reorganizar a estrutura administrativa, valorizar a participa\u00e7\u00e3o das mulheres Soamarinas e ampliar a coopera\u00e7\u00e3o com outras institui\u00e7\u00f5es sociais do Maranh\u00e3o;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> S\u00edlvio L\u00facio de Oliveira Aguiar (2021\/2022 at\u00e9 os dias atuais), sob cuja gest\u00e3o a Soamar\/MA viveu um dos per\u00edodos mais ativos de sua hist\u00f3ria recente.<\/em><\/span><\/li>\r\n<\/ul>\r\n<p><img decoding=\"async\" class=\"alignnone wp-image-31286 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-03.jpg\" alt=\"\" width=\"900\" height=\"548\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-03.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-03-300x183.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-03-768x468.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><span style=\"color: #000000;\"><strong>Feitos que Marcaram Nossa Hist\u00f3ria Recente:<\/strong><\/span><\/p>\r\n<p><span style=\"color: #000000;\"><strong>Entre tantas realiza\u00e7\u00f5es no decorrer dos 47 anos, desses destacamos:<\/strong><\/span><\/p>\r\n<ul>\r\n<li><span style=\"color: #000000;\"><em> Reforma geral e entrega aos Soamarinos do pr\u00e9dio sede no Complexo do Jenipapeiro durante as gest\u00f5es de 2011 a 2013;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Implanta\u00e7\u00e3o do Museu Mar\u00edtimo da SOAMAR\/MA;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em>Renova\u00e7\u00e3o do Quadro de s\u00f3cios dos Soamarinos saindo de 26 s\u00f3cios em 2011 para 87 s\u00f3cios em 2026;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Entregas de dezenas de Medalhas Amigo da Marinha a personalidades civis e militares que se distinguiram na defesa da mentalidade mar\u00edtima;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Reuni\u00e3o das Soamar Regionais do 4\u00b0 Distrito Naval em 2015;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Organiza\u00e7\u00e3o junto \u00e0 Soamar Brasil do XXI Encontro Nacional de Presentes das Soamar do Brasil com a posse do Presidente da Soamar Brasil para o per\u00edodo de 2016 a 2018, em 2016;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Diversas A\u00e7\u00f5es Sociais e Culturais com apoio de Empresas parceiras e dos Soamarinos (2011 a 2026);<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Primeiro Conv\u00eanio estabelecido com uma Autoridade Portu\u00e1ria, no caso a Empresa Maranhense de Administra\u00e7\u00e3o Portu\u00e1ria\/EMAP, especialmente, tendo como foco principal o estreitamento das rela\u00e7\u00f5es Porto\/Cidade, em relevante sintonia com os ideais da Marinha do Brasil e Sociedade Civil;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> Apoio \u00e0 Marinha do Brasil por ocasi\u00e3o dos Eventos que envolveram o anivers\u00e1rio de 200 anos da Independ\u00eancia do Brasil e 200 anos da Esquadra da Marinha do Brasil;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> A realiza\u00e7\u00e3o do tradicional Coquetel Maranh\u00e3o Mar\u00edtimo, encerrando cada ano com a comunidade portu\u00e1ria maranhense;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> O apoio \u00e0 publica\u00e7\u00e3o de obras culturais sobre a hist\u00f3ria mar\u00edtima do Maranh\u00e3o, em parceria com a EMAP;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> A inaugura\u00e7\u00e3o da est\u00e1tua do Almirante Tamandar\u00e9, marco de nossa mem\u00f3ria naval;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> A\u00e7\u00f5es sociais cont\u00ednuas, como a entrega de cestas b\u00e1sicas a fam\u00edlias carentes e celebra\u00e7\u00f5es em datas como o Dia das M\u00e3es;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> A de sediar, em S\u00e3o Lu\u00eds, a XXIII Conven\u00e7\u00e3o Nacional da Soamar Brasil, em 2023, reunindo Soamarinos de todo o pa\u00eds em nossa &#8220;Atenas Brasileira&#8221;;<\/em><\/span><\/li>\r\n<li><span style=\"color: #000000;\"><em> E, em 2024, a comemora\u00e7\u00e3o marcante dos 45 anos de nossa entidade \u2014 um marco que hoje, dois anos depois, se renova nestes 47 anos de exist\u00eancia.<\/em><\/span><\/li>\r\n<\/ul>\r\n<p><span style=\"color: #000000;\">A cada gest\u00e3o, a cada diretoria, a cada Soamarino e Soamarina que aqui passou, devemos gratid\u00e3o. \u00c9 esse trabalho coletivo, sempre em parceria com a Capitania dos Portos do Maranh\u00e3o, com a Marinha do Brasil e com as empresas portu\u00e1rias de nosso estado, que faz da Soamar\/MA o verdadeiro bra\u00e7o civil da Marinha em terras maranhenses.<\/span><\/p>\r\n<p><span style=\"color: #000000;\">Agrade\u00e7o, tamb\u00e9m, a todos os outros Presidentes que deixaram suas contribui\u00e7\u00f5es para o fortalecimento da Associa\u00e7\u00e3o no Maranh\u00e3o.<\/span><\/p>\r\n<p><span style=\"color: #000000;\">Que os pr\u00f3ximos anos sigam escrevendo cap\u00edtulos t\u00e3o honrosos quanto os que j\u00e1 vivemos.<\/span><\/p>\r\n<h5><strong><span style=\"color: #000000;\"><span style=\"color: #800000;\">S\u00edlvio L\u00facio de Oliveira Aguiar<\/span><br><\/span><\/strong><span style=\"color: #000000;\">Parab\u00e9ns, Soamar Maranh\u00e3o! Avante, Soamarinos!<\/span><span style=\"color: #000000;\"><br><\/span><span style=\"color: #000000;\">Viva a Marinha do Brasil!!<br><\/span><span style=\"color: #000000;\">Sauda\u00e7\u00f5es Soamarinas.<\/span><\/h5>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-31285 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-02.jpg\" alt=\"\" width=\"900\" height=\"494\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-02.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-02-300x165.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-02-768x422.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<figure id=\"attachment_31288\" aria-describedby=\"caption-attachment-31288\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31288 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-05.jpg\" alt=\"\" width=\"900\" height=\"213\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-05.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-05-300x71.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-05-768x182.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-31288\" class=\"wp-caption-text\"><span style=\"color: #800000;\"><em><strong>Na imensa galeria dos not\u00e1veis, patriarcas como Herc\u00edlio Luz Sim\u00f5es. M\u00e1rio Flexa Ribeiro, Carlo Amorim, Antntonio Rufino Filho, Jorge Afonso e Jobert Jos\u00e9 Salgado Filho.<\/strong><\/em><\/span><\/figcaption><\/figure>\r\n<h3>A\u00e7\u00e3o social na Creche Vov\u00f3 Dolores<\/h3>\r\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-29543 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/04\/CESTAS-BASICAS.jpg\" alt=\"\" width=\"900\" height=\"589\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/04\/CESTAS-BASICAS.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/04\/CESTAS-BASICAS-300x196.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/04\/CESTAS-BASICAS-768x503.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/h3>\r\n<p>A SOAMAR &#8211; Sociedade dos Amigos da Marinha do Estado do Maranh\u00e3o, realizou a entrega de cestas b\u00e1sicas \u00e0s fam\u00edlias carentes no Jardim de Inf\u00e2ncia e Creche Vov\u00f3 Dolores, localizada no Bairro do S\u00e3o Francisco. A a\u00e7\u00e3o solid\u00e1ria foi uma iniciativa do projeto social da entidade, sob a coordena\u00e7\u00e3o do presidente S\u00edlvio L\u00facio Aguiar, com o apoio do vice-presidente Rog\u00e9rio Ferreira, da diretora social Tamara Vi\u00e9gas e da secret\u00e1ria executiva Valdina Borges. A foto registra o momento da entrega com a equipe da Soamar, as m\u00e3es beneficias e a diretora da crece\/escola.<\/p>\r\n<h3>Palavra do Presidente pelos 45 anos da entidade<\/h3>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15580 size-full alignleft\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/06\/SILVIO.jpg\" alt=\"\" width=\"215\" height=\"274\"><\/p>\r\n<p>Caros Soamarinos do Maranh\u00e3o,<\/p>\r\n<p>\u00c9 com muita satisfa\u00e7\u00e3o que tenho a honra de poder me congratular e tamb\u00e9m representar a Sociedade Amigos da Marinha do Maranh\u00e3o no dia de hoje que representa o 45\u00ba anivers\u00e1rio de cria\u00e7\u00e3o da Sociedade de Amigos da Marinha do Estado do Maranh\u00e3o, SOAMAR-MA. Em comemora\u00e7\u00e3o a esta feliz data, parece adequado, portanto, fazer um pequeno hist\u00f3rico a respeito da nossa t\u00e3o alvissareira entidade.<\/p>\r\n<p>Nossa Institui\u00e7\u00e3o de 45 anos, completos neste 18 de Junho, foi criada na forma idealizada pelo ent\u00e3o Ministro da Marinha e Patrono da SOAMAR, Almirante de Esquadra Maximiano Eduardo Silva da Fonseca, tem como umas de suas finalidades, tamb\u00e9m, a de congregar pessoas e personalidades que tenham recebido a Medalha \u201cAmigo da Marinha\u201d, ou condecoradas pela Marinha do Brasil.<\/p>\r\n<p>Al\u00e9m disso, a Soamar Maranh\u00e3o mant\u00e9m um trabalho de difus\u00e3o de conceitos doutrin\u00e1rios e culturais relativos a assuntos do mar e dos projetos de nossa Marinha do Brasil, assim como a import\u00e2ncia pol\u00edtica, estrat\u00e9gica e econ\u00f4mica para o Maranh\u00e3o e Brasil de tudo aquilo que de alguma forma, se relacione com o Poder Mar\u00edtimo.<\/p>\r\n<p>A Soamar do Maranh\u00e3o, assim como todas as demais Soamares existentes em territ\u00f3rio brasileiro \u00e9 tamb\u00e9m conhecida como o bra\u00e7o civil da Marinha aqui no Maranh\u00e3o. Como toda Associa\u00e7\u00e3o, seguimos nosso Estatuto, o qual nos aproxima muito e possibilita assinar este Protocolo de Inten\u00e7\u00f5es junto a Institui\u00e7\u00f5es ilibadas e que tem como fim os mesmos ideais sociais e culturais da entidade a qual fazemos parte.<\/p>\r\n<p><em>A Soamar Maranh\u00e3o iniciou sua hist\u00f3ria quando de sua funda\u00e7\u00e3o, no dia 18 de Junho de 1979. S\u00e3o 45 anos j\u00e1 completos desde sua cria\u00e7\u00e3o e posse de seu primeiro presidente, o historiador e poeta Mario Martins Meirelles. De l\u00e1 para c\u00e1 foram v\u00e1rios presidentes, cada um deixando o seu legado e construindo a cada administra\u00e7\u00e3o, a enorme reputa\u00e7\u00e3o social e hist\u00f3rica de sucesso de nossa Soamar.<\/em><\/p>\r\n<p><em>Faz parte do DNA da Soamar maranhense, e dos soamarinos, a realiza\u00e7\u00e3o de a\u00e7\u00f5es sociais e eventos c\u00edvicos-militares, sempre em coopera\u00e7\u00e3o e coparticipa\u00e7\u00e3o das nossas empresas portu\u00e1rias, demais for\u00e7as aqui constitu\u00eddas e, principalmente, da Capitania do Portos do Maranh\u00e3o, hoje sob o Comandando do CMG <\/em>&nbsp;Alessandro Domingos Gurski.<\/p>\r\n<p>Finalmente, gostaria de agradecer a todos os meus companheiros de diretorias, soamarinos, entidades c\u00edvicos-militares e a sociedade cilvil em geral pelo apoio e pela confian\u00e7a em delegar a mim o cargo de presidente da minha e da nossa Sociedade de Amigos da Marinha do Estado do Maranh\u00e3o.<\/p>\r\n<p>Sauda\u00e7\u00f5es Soamarinas!<br><br><strong>S\u00edlvio L\u00facio de Oliveira Aguiar<\/strong><br><em>Presidente da Soamar Maranh\u00e3o<\/em><span style=\"color: #333399;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15578 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/06\/NIVER-SOAMAR-2.jpg\" alt=\"\" width=\"800\" height=\"843\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/06\/NIVER-SOAMAR-2.jpg 800w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/06\/NIVER-SOAMAR-2-285x300.jpg 285w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/06\/NIVER-SOAMAR-2-768x809.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13040 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-6.jpg\" alt=\"\" width=\"900\" height=\"470\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-6.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-6-300x157.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-6-768x401.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><br><\/span><\/p>\r\n<h4><span style=\"color: #000000;\">Capitania do Maranh\u00e3o e Soamar entregam mais uma Medalha Amigo da Marinha<\/span><\/h4>\r\n<p><span style=\"color: #000000;\">Depois de condecorar 30 personalidades com A Medalha de Amigo, a Marinha do Brasil, atrav\u00e9s da Capitania dos Portos do Estado do Maranh\u00e3o, e a Soamar, promoveu uma sess\u00e3o especial de outorga desta que \u00e9 uma das maiores comenda da For\u00e7a dedicada a personalidades civis, e militares de For\u00e7as amigas como Ex\u00e9rcito, Policia Federal, Policia Militar, Aeron\u00e1utica e Policia Rodovi\u00e1ria Federal.<\/span><\/p>\r\n<p><span style=\"color: #000000;\">Listado entre os agraciados na cerim\u00f4nia de dezembro de 2023, Leonardo Cahu\u00ea Martins, por motivos alheios e compromissos profissionais fora da capital maranhense, n\u00e3o compareceu.<\/span><\/p>\r\n<p><span style=\"color: #000000;\">Agora, com agenda de trabalho em S\u00e3o Lu\u00eds, ele aproveitou a oportunidade, e a data, para receber, enfim, a sua Medalha Amigo da Marinha.<\/span><\/p>\r\n<p><span style=\"color: #000000;\">A cerim\u00f4nia de entrega aconteceu no \u00faltimo dia 15 de fevereiro e foi presidida pelo CMG Alessandro Domingos Gurski, Capit\u00e3o dos Portos do Maranh\u00e3o, e Silvio L\u00facio de Oliveira Aguiar, presidente da Sociedade Amigos do Estado do Maranh\u00e3o. Al\u00e9m destes, tamb\u00e9m se fizeram presentes, membros da diretoria da Soamar, soamarinos, empres\u00e1rios do setor portu\u00e1rio e o suboficial Chagas, que atuou como mestre de cerim\u00f4nia. Veja as fotos.<\/span><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13041 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-7.jpg\" alt=\"\" width=\"900\" height=\"395\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-7.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-7-300x132.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-7-768x337.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13035 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-1.jpg\" alt=\"\" width=\"900\" height=\"499\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-1.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-1-300x166.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-1-768x426.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13036 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-2.jpg\" alt=\"\" width=\"900\" height=\"316\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-2.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-2-300x105.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-2-768x270.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13037 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-3.jpg\" alt=\"\" width=\"900\" height=\"347\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-3.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-3-300x116.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-3-768x296.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13038 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-4.jpg\" alt=\"\" width=\"900\" height=\"417\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-4.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-4-300x139.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-4-768x356.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <br><br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13039 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-5.jpg\" alt=\"\" width=\"900\" height=\"415\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-5.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-5-300x138.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2024\/02\/CAUE-5-768x354.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>&nbsp;<\/p>\r\n<p>Leia tamb\u00e9m:<br><a href=\"https:\/\/portosma.com.br\/index.php\/2023\/11\/11\/capitania-e-soamar-entregam-medalha-amigo-da-marinha\/\"><span style=\"color: #808080;\"><strong>Marinha, Capitania e Soamar entregam novas Medalhas de Amigo da Marinha<\/strong><\/span><\/a><\/p>\r\n<h3>Soamar\/Emap promovem coquetel Maranh\u00e3o Mar\u00edtimo 2023<br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11466 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-01.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-01.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-01-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-01-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/h3>\r\n<p><strong>16.12.2023<\/strong> &#8211; Ainda dentro do projeto conveniado entre a Emap \u2013 Empresa Maranhense de Administra\u00e7\u00e3o Portu\u00e1ria, e a Soamar-MA \u2013 Sociedade dos Amigos da Marinha do Maranh\u00e3o, esta \u00faltima promoveu, na \u00faltima sexta-feira, 15\/12, o Coquetel Maranh\u00e3o Mar\u00edtimo 2023. O evento serviu como forma de encerramento, e confraterniza\u00e7\u00e3o da comunidade mar\u00edtima maranhense, juntamente com as autoridades portu\u00e1rias constitu\u00eddas \u2013 representada por oficiais de Marinha e o Capit\u00e3o dos Portos do Maranh\u00e3o, CMG Alexandre Roberto Janu\u00e1rio \u2013 do ano de 2023, marcado por in\u00fameras atividades c\u00edvicas militares.<\/p>\r\n<p>Entre as quais palestras, entrega de medalhas de Amigo da Marinha, inaugura\u00e7\u00e3o do busto do Almirante Tamandar\u00e9, encontro de Capit\u00e3es dos Portos, e, mais recentemente, cerim\u00f4nia e exposi\u00e7\u00e3o em comemora\u00e7\u00e3o ao Dia do Marinheiro. Durante a solenidade foi feito o lan\u00e7amento do livro \u201c<strong><em>Ina, a viola\u00e7\u00e3o do Sagrado<\/em><\/strong>\u201d, do escritor Mhario Lincoln. Maranhense e soamarino, ele conta, em um excelente trabalho de pesquisa hist\u00f3rico dos mais relevantes, como aconteceram alguns dos principais acidentes mar\u00edtimos j\u00e1 ocorridos no Maranh\u00e3o.<\/p>\r\n<p>\u201cO livro, agora em sua terceira edi\u00e7\u00e3o, foi reeditado gra\u00e7as a parceria entre Soamar\/Emap que tem por objetivo maior, exaltar tudo que for relevante para o engrandecimento do nosso complexo portu\u00e1rio\u201d, afirmou S\u00edlvio L\u00facio de Oliveira Aguiar, presidente da Sociedade Amigos da Marinha do Estado do Maranh\u00e3o. Veja algumas fotos do evento.<\/p>\r\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11475 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-10.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-10.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-10-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-10-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/h3>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11469 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-04.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-04.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-04-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-04-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11471 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-06.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-06.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-06-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-06-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11468 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-03.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-03.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-03-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-03-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11472 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-07.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-07.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-07-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-07-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11473 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-08.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-08.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-08-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-08-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11467 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-02.jpg\" alt=\"\" width=\"900\" height=\"364\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-02.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-02-300x121.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-02-768x311.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11470 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-05.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-05.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-05-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-05-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11474 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-09.jpg\" alt=\"\" width=\"900\" height=\"405\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-09.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-09-300x135.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-09-768x346.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11476 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-11.jpg\" alt=\"\" width=\"900\" height=\"436\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-11.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-11-300x145.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-11-768x372.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/> <br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11477 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-12.jpg\" alt=\"\" width=\"900\" height=\"442\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-12.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-12-300x147.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/12\/NATAL-12-768x377.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<h3>13.05.2023 &#8211; Soamar do Maranh\u00e3o celebra o Dia das M\u00e3es ano 2023<\/h3>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9570 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/09\/SOASECRET.jpg\" alt=\"\" width=\"900\" height=\"626\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/09\/SOASECRET.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/09\/SOASECRET-300x209.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/09\/SOASECRET-768x534.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6735 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/05\/MAE-SOAMAR.jpg\" alt=\"\" width=\"900\" height=\"604\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/05\/MAE-SOAMAR.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/05\/MAE-SOAMAR-300x201.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/05\/MAE-SOAMAR-768x515.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<h4>S\u00edlvio L\u00facio de Oliveira \u00e9 aclamado como o nov0 presidente da Soamar do Maranh\u00e3o<\/h4>\r\n<figure id=\"attachment_4114\" aria-describedby=\"caption-attachment-4114\" style=\"width: 350px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4114 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-1.jpg\" alt=\"\" width=\"350\" height=\"247\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-1.jpg 350w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-1-300x212.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><figcaption id=\"caption-attachment-4114\" class=\"wp-caption-text\"><span style=\"color: #993300;\"><em><strong>Silvio, j\u00e1 aleito, fala aos presentes durante a solenidade<\/strong><\/em><\/span><\/figcaption><\/figure>\r\n<p><strong>(03\/07\/2021)<\/strong> &#8211; Depois do impasse por conta de desencontros de opini\u00f5es por observ\u00e2ncia ou n\u00e3o do Estatuto da Soamar-MA, a Sociedade de Amigos da Marinha, finalmente, realizou a elei\u00e7\u00e3o da sua Diretoria Executiva, gra\u00e7as a denomina\u00e7\u00f5es expressas do Capit\u00e3o dos Portos, Alekson Barbosa da Silva Porto, que, na condi\u00e7\u00e3o de Presidente do Conselho Superior da Soamar-MA e, considerando que o prazo da atual diretoria j\u00e1 havia expirado, usou de toda sua autoridade para dar uma solu\u00e7\u00e3o que encaminhasse para o fim do impasse. Em um esfor\u00e7o adicional e, \u00fanico, considerando os incidentes e at\u00e9 mesmo inconvenientes ocorridos no dia 10 de junho, quando \u00e2nimos se exaltaram e o pleito saiu do controle, o mesmo Capit\u00e3o dos Portos que suspendera aquela sess\u00e3o,&nbsp; voltou a reunir os dois presidentes envolvidos na disputa. No caso, S\u00edlvio L\u00facio de Oliveira Aguiar (Chapa Almirante In\u00e1cio Belfort Vieira), e Carlos Guterres Moreira (Chapa Jobert Jos\u00e9 Salgado Filho). A ideia era aparar arestas e costurar um acordo de modo a manter a tranquilidade e o espirito de amigo Soamarinos que define a entidade. N\u00e3o conseguiu. As convic\u00e7\u00f5es conflitantes do dia 10 foram mantidas e, sem alterar uma v\u00edrgula do documento base da primeira elei\u00e7\u00e3o, ficou determinado que uma nova elei\u00e7\u00e3o seria realizada no dia 01 de julho de 2021.<\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4116 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-3.jpg\" alt=\"\" width=\"900\" height=\"230\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-3.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-3-300x77.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-3-768x196.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p>Mantinha-se assim o impasse: sem consenso, ficaria mantido o s votos dos S\u00f3cios Natos _ vota e serem votados -, assim como a validade para os votos por procura\u00e7\u00e3o, uma das diverg\u00eancias que mais gerou disc\u00f3rdias na elei\u00e7\u00e3o frustrada do dia 10 de junho.<\/p>\r\n<p>Sem acordo, apesar da decis\u00e3o do Capit\u00e3o dos Portos \u2013 leia documento no final da reportagem \u2013 que reconheceu como v\u00e1lido os argumentos da Chapa da situa\u00e7\u00e3o, o presidente da chpa de oposi\u00e7\u00e3o Carlos Guterres Moreira, em nome de todos os demais nomes da chapa, decidiu abandonar o pleito e retirar a candidatura. Um documento oficializando a decis\u00e3o da Soamar-MA foi entregue e protocolado no dia 28 de junho, dois dias antes da data da nova elei\u00e7\u00e3o.<\/p>\r\n<p>A decis\u00e3o da Chapa de Carlos Guterres Moreira que abriu caminho para S\u00edlvio e seus companheiros que s\u00f3 precisariam se aclamados, considerados o pleito ter se tornado de \u201cchapa \u00fanica\u201d, onde apenas um voto seria suficiente para a elei\u00e7\u00e3o.<\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4117 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-4.jpg\" alt=\"\" width=\"900\" height=\"256\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-4.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-4-300x85.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/AFOTO-SILVIO-4-768x218.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p>Desse modo,&nbsp; nesta quinta-feira, dia primeiro de julho de 2021, o pr\u00f3prio Comandante Porto abriu os trabalhos, leu sua pr\u00f3pria decis\u00e3o considerando legal os tramites do pleito, e pediu ao Soamarinos Luiz In\u00e1cio Corr\u00eaa Filho que lesse a carta-ren\u00fancia da chapa desistente. Feito isso, foi aberta uma vota\u00e7\u00e3o simb\u00f3lica dos membros presentes da chapa \u201cChapa Almirante In\u00e1cio Belfort Vieira\u201d, ato considerado suficiente para torna-la eleita, por aclama\u00e7\u00e3o, assumindo imediatamente a diretoria da Sociedade dos Amigos da Marinha do Maranh\u00e3o.<\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong>CHAPA VENCEDORA: ALMEIRANTE MANOEL BELFOR VIEIRA<\/strong><\/span><\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong>DIRETORIA EXECUTIVA<\/strong><\/span><\/p>\r\n<p style=\"text-align: center;\">*** Presidente: S\u00edlvio L\u00facio de Oliveira Aguiar<br>*** 1\u00ba Vice-presidente: L\u00eddia Pflueguer dos Santos<br>*** 3\u00ba Vice-Presidente: Luiz In\u00e1cio Corr\u00eaa Filho<br>*** Diretor Cultural: M\u00e1rcio Vaz dos Santos<\/p>\r\n<p style=\"text-align: center;\"><strong><span style=\"color: #3366ff;\">CONSELHO DELIBERATIVO (TITULARES)<\/span><\/strong><\/p>\r\n<p style=\"text-align: center;\">*** Luiz Augusto de Miranda Guterres Filho<br>*** Luiz Carlos Cantanhede Fernandes<br>*** Jos\u00e9 Gon\u00e7alves dos Santos Neto<br>*** Carlos Augusto Furtado Moreira<\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong>CONSELHO DELIBERATIVO (SUPLENTES)<\/strong><\/span><\/p>\r\n<p style=\"text-align: center;\">*** Ricardo Micucci dos Santos<br>*** Nilo Alberto Monteiro de Carvalho<br>*** Jos\u00e9 Roberto Taranto<\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong>CONSELHO FISCAL (TITULARES)<\/strong><\/span><\/p>\r\n<p style=\"text-align: center;\">*** Carlos Eduado Brand\u00e3o de Albuquerque Neves<br>*** Ricardp Reis Rebelo<br>*** Nelson Ricardo Calmom Bahia<\/p>\r\n<p style=\"text-align: center;\"><strong><span style=\"color: #3366ff;\">CONSELHO FICAL (SUPLENTES)<\/span><\/strong><\/p>\r\n<p style=\"text-align: center;\">*** Sebasti\u00e3o Sousa da Silva Filho<br>*** Oswaldo Ferreira do Prado Fanco<br>*** Josivaldo Freire Reis<\/p>\r\n<h4 style=\"text-align: center;\">DIRETORIA ANTERIOR<br><br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3754 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-2.jpg\" alt=\"\" width=\"900\" height=\"462\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-2.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-2-300x154.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-2-768x394.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/h4>\r\n<p style=\"text-align: center;\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif;\"><span style=\"font-size: large;\">Numa elei\u00e7\u00e3o de chapa \u00fanica foi eleita a nova Diretoria Executiva da Sociedade de Amigos da Marinha no Estado do Maranh\u00e3o &#8211; SOMAR-MA, tendo a frente, pela primeira vez, Jobert Jos\u00e9 Salgado Filho. Ele ser\u00e1 o presidente da entidade pelos pr\u00f3ximos dois anos, considerando que foi eleito para o bi\u00eanio 2019\/2021. A chapa eleita \u00e9 a seguinte:<\/span><\/span><\/p>\r\n<p align=\"center\"><span style=\"color: #990000; font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\"><strong>DIRETORIA EXECUTIVA<\/strong><\/span><\/p>\r\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\">Presidente: JOBERT JOS\u00c9 SALGADO FILHO<br>1\u00ba Vice-Presidente: JORGE AFONSO GUAQLIANE PEREIRA<br>2\u00ba Vice-Presidente: S\u00cdLVIO L\u00daCIO DE OLIVEIRA AGUIAR<\/span><\/p>\r\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\">CONSELHO DELIBERATIVO &#8211; TITULARES<\/span><\/p>\r\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\">1 &#8211; CARLOS GUTERRES MOREIRA<br>2 &#8211; RUBEM OMAR ROVIRA<br>3 &#8211; RONILDO JOS\u00c9 SOARES DE CARVALHO<br>4 &#8211; JOS\u00c9 RAIMUNDO NOGUEIRA DOS SANTOS<\/span><\/p>\r\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\">CONSELHO DELIBERATIVO &#8211; SUPLENTES<\/span><\/p>\r\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\">1 &#8211; LUIS CARLOS CANTANH\u00caDE FERNANDE<br>2 &#8211; NEM\u00c9SIO BRAND\u00c3O NEVES<br>3 &#8211; JOS\u00c9 ROBERTO TARANTO<br>4 &#8211; LUCIANA MARIA RIBEIRO MORAES R\u00caGO<\/span><\/p>\r\n<p align=\"center\"><span style=\"color: #990000; font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\"><strong>CONSELHO FISCAL &#8211; TITULARES<\/strong><\/span><\/p>\r\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\">1 &#8211; COMANDANTE CARLOS EDUARDO ALBUQUERQUE ALVES<br>2 &#8211; EUL\u00c1LIA DAS NEVES FERREIRA<br>3 &#8211; DORIAN RIKER TELES DE MENESES<\/span><\/p>\r\n<p align=\"center\"><span style=\"color: #990000; font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\"><strong>CONSELHO FISCAL &#8211; SUPLENTES<\/strong><\/span><\/p>\r\n<p align=\"center\"><span style=\"font-family: Verdana, Arial, Helvetica, sans-serif; font-size: medium;\">1 &#8211; ALFREDO DE SOUSA<br>2 &#8211; NILO ALBERTO MONTEIRO CARVALHO<br>3 &#8211; C\u00c9LIA DA C\u00c2MARA BATISTA<br><\/span><\/p>\r\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5099 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-PANORAMICA.jpg\" alt=\"\" width=\"900\" height=\"276\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-PANORAMICA.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-PANORAMICA-300x92.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/SOAMAR-PANORAMICA-768x236.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-31287 size-full\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg\" alt=\"\" width=\"900\" height=\"494\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg 900w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04-300x165.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04-768x422.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\r\n<p><span style=\"color: #800000;\"><strong>Escrever a hist\u00f3ria da Soamar \u2013 Sociedade Amigos da Marinha do Estados do Maranh\u00e3o, sem lembrar dos seus baluartes, seus pioneiros, de homens que, alguns vindos de bem longe como Herc\u00edlio Luz Sim\u00f5es e M\u00e1rio Flexa, adotaram o Estado como \u201cp\u00e1tria amada\u201d e a Marinha como amiga. Foi assim, com essa reciprocidade que s\u00f3 as verdadeiras amizades s\u00e3o capazes de produzir, que nasceu esta entidade cuja miss\u00e3o maior, \u00e9 \u201clinkar\u201d a sociedade civil maranhense com os conceitos nobres e \u00e9ticos que que a Marinha tem, e que aceitou, de bom grado, e de m\u00e9rito, acolher, junto aos seus pares, esses cidad\u00e3os conhecidos em todo o pa\u00eds pelo nome de soamarinos. Hoje, 47 anos depois, a Soamar do Maranh\u00e3o tem como diretor presidente S\u00edlvio L\u00facio de Oliveira Aguiar e, a Soamar Brasil \u2013 que j\u00e1 teve entre os seus mandat\u00e1rios \u201cmaranhenses\u201d como Herc\u00edlio Luz Sim\u00f5es e Orson Ant\u00f4nio Feres Moraes Rego \u2013 \u00e9 comandada pelo cearense Jorge Eduardo Pessoa Arag\u00e3o.<\/strong><\/span><\/p>\r\n<p><span style=\"color: #3366ff;\"><strong>SOAMAR DO MARANH\u00c3O\/HIST\u00d3RIA<\/strong> <\/span>\u2013 <span style=\"color: #000000;\">Fundada no dia 18 de junho de 1979, a Soamar surgiu como institui\u00e7\u00e3o no Maranh\u00e3o gra\u00e7as ao idealismo de um grupo de pessoas, residentes e domiciliadas em S\u00e3o Lu\u00eds, que agraciados como os primeiros Amigos da Marinha no Maranh\u00e3o, e s\u00f3cios fundadores, se reuniram em Assembl\u00e9ia Geral em uma das salas do por\u00e3o da Capitania dos Portos e criaram a Sociedade Amigos da Marinha do Estado do Maranh\u00e3o. Seu primeiro presidente foi o eminente escritor e jornalista M\u00e1rio Martins Meireles. Figuram como s\u00f3cios fundadores as seguintes personalidades: Luiz da Rocha Porto; Francisco Guimar\u00e3es e Souza; Luiz M\u00e1gno Portella Passos; Jos\u00e9 Duailibe Murad; Elimar Figueiredo de Almeida e Silva; Haroldo Olympio Lisboa Tavares; Moyses Tajra; M\u00e1rio Martins Meireles; Glacimar Ribeiro Marques; Gild\u00e1sio L\u00e9lis Fonseca; Voltare Fraz\u00e3o; Paulo Castelo Branco; Elyr de Jesus Gomes; Benedito Salim Duailibe; Jos\u00e9 Jamenes Calado; Carmelino Mota; Pedro Neiva de Santana e Alexandre de S\u00e1 Colares Moreira. A primeira diretoria da Soamar-MA ficou assim constitu\u00edda:<\/span><\/p>\r\n<p><span style=\"color: #3366ff;\"><strong>CONSELHO SUPERIOR:<\/strong><\/span> Presidente Nato: Comandante do III DN (Na oportunidade a Capitania do Maranh\u00e3o ainda era subordinada ao Terceiro Distrito Naval, hoje \u00e9 subordinada ao Quarto Distrito)<\/p>\r\n<p><span style=\"color: #3366ff;\"><strong>MEMBROS NATO:<\/strong><\/span> Capit\u00e3o dos Portos do Marah\u00e3o (na \u00e9poca o Capit\u00e3o de Mar e Guerra Frank Jos\u00e9 Gon\u00e7alves Oliveira).<\/p>\r\n<p><span style=\"color: #3366ff;\"><strong>MEMBROS:<\/strong><\/span> Elyr de Jesus Gomes, Jos\u00e9 Duailibe Murad, Francisco Guimar\u00e3es e Sousa, Alexandre de S\u00e1 Colares Moreira e Carlos de Sousa Vasconcelos.<\/p>\r\n<p><span style=\"color: #3366ff;\"><strong>DIRETORIA EXECUTIVA:<\/strong><\/span> M\u00e1rio Martins Meireles (Presidente); Pedro Neiva de Santana (Vice-presidente); Luiz Magno Portela Passos (Secret\u00e1rio); Jos\u00e9 Ribamar Avelar (2\u00ba secret\u00e1rio); Glacimar Ribeiro Marques (Tesoureiro); Benedito Salim Duailibi (2\u00ba tesoureiro); Bernardo Coelho de Almeida (Diretor Social e Cultural); Jos\u00e9 Jamenes Calado (Diretor de Rela\u00e7\u00f5es P\u00fablicas).<\/p>\r\n<p><span style=\"color: #3366ff;\"><strong>CONSELHO FISCAL:<\/strong><\/span> Haroldo Olympio Lisboa Tavares, Luiz da Rocha Porto e Moises Tajra.<\/p>\r\n<p>Depois de M\u00e1rio Meireles, o sucederam na presid\u00eancia os s\u00f3cios efetivos Elyr de Jesus Gomes, Domingos dos Santos Martins Filho, Herc\u00edlio Luz Sim\u00f5es (que tamb\u00e9m foi presidente da Soamar Brasil), Ab\u00edlio S\u00edlvio Gurgel, M\u00e1rio Flexa Ribeiro, Ant\u00f4nio Rufino Filho, Carlos Guterres, Rui Ilyano Abreu, Osvaldo Pereira Rocha, Carlos Ramos Amorim, Manoel de Jesus Bastos, Jorge Afonso GuaglianI Pereira, Orson Ant\u00f4nio Feres Moraes R\u00eago (atual presidente da Soamar Brasil), Ricardo Micucci dos Santos, Jobert Jos\u00e9 Salgado Filho&nbsp; e S\u00edlvio L\u00facio de Oliveira Aguiar (presidente atual) . Seu atual presidente \u00e9 o soamarino S\u00edlvio Aguiar. Durante os seus 41 anos de exist\u00eancia, a Soamar do Maranh\u00e3o j\u00e1 conviveu de ordem p\u00e1cifica e ordeira com os seguites comandantes da CPMA: Frank Oliveira, Luis Fernando Freitas, Gustavo Bentemuller, Sidney Oliveira, Gilberto Esmeraldo, Amilcar Rodrigues, Wilson Baltor, Carlos Alberto Santos Ramos, Od\u00e1lio Amorim, Carlos Alberto Trov\u00e3o, Elson de Azevedo Burity, Enilson Vilela, Luiz Augusto Freitas, Faria Melo, Luiz Carlos de Melo, Ricardo Calmon Bahia, Jair dos Santos Oliveira, Marcos Tadashi, Andr\u00e9 Luiz Trindade e M\u00e1rcio Ramalho Dutra e Mello. Atualmente o presidente da Soamar \u00e9 o soamarino S\u00edvio Guiar, e o presidente do Conselho Superior, \u00e9 o CMG Alekson Barbosa da Silva PORTO, Capit\u00e3o dos Portos do Estado do Maranh\u00e3o.<\/p>\r\n<p><span style=\"color: #0000ff;\"><strong>LISTA OFICIAL DE TODOS OS PRESIDENTES DA SOAMAR DO MARANH\u00c3O<\/strong><\/span><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5067\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-01.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5068\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-02.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5069\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-03.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5070\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-04.jpg\" alt=\"\" width=\"215\" height=\"274\"><br><span style=\"color: #993300;\"><strong>01<\/strong><\/span> &#8211; <strong>M\u00e1rio Martins Meireles<\/strong> (1978\/1981); <span style=\"color: #993300;\"><strong>02<\/strong><\/span> &#8211; <strong>Elir de Jesus Gomes<\/strong> (1981\/1983); <span style=\"color: #993300;\"><strong>03<\/strong><\/span> &#8211;<strong>Domingos<\/strong> <strong>dos Santos Martins Filho<\/strong> (1983\/1985); <span style=\"color: #993300;\"><strong>04<\/strong><\/span> &#8211; <strong>Herc\u00edlio Luz Sim\u00f5es<\/strong> (1985\/1989 &#8211; 1991\/1993).<br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5071\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-05.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5072\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-06.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5073\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-07.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5083\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-08.jpg\" alt=\"\" width=\"215\" height=\"274\"><br><span style=\"color: #993300;\"><strong>05<\/strong><\/span> &#8211; <strong>M\u00e1rio Flexa Ribeiro<\/strong> (1989\/1981 &#8211; 1993\/1997); <span style=\"color: #993300;\"><strong>06<\/strong><\/span> &#8211; <strong>Carlos Ramos Amorim<\/strong> (1997\/1997); <span style=\"color: #993300;\"><strong>07<\/strong><\/span> <strong>Ruy Illayno Co\u00ealho Abreu<\/strong> (199\/2001); <span style=\"color: #993300;\"><strong>08<\/strong><\/span> &#8211; <strong>Ant\u00f4nio Rufino Filho<\/strong> (2001\/2003).<br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5075\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-09.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5076\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-10.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5077\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-11.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5078\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-12.jpg\" alt=\"\" width=\"215\" height=\"274\"><br><strong><span style=\"color: #993300;\">09<\/span> &#8211; Manoel de Jesus Moreira Bastos<\/strong> (2003\/2005); <strong><span style=\"color: #993300;\">10<\/span> &#8211; Jorge Afonso Guagliani Pereira<\/strong> (2005\/2007 &#8211; 2007\/2009 &#8211; 2009\/2011); <strong><span style=\"color: #993300;\">11<\/span> &#8211; Orson Ant\u00f4nio Feres Moraes R\u00eago<\/strong> (2011\/2013 &#8211; 2013\/2015);<strong><span style=\"color: #993300;\"> 12<\/span> &#8211; Ricardo Miccuci dos Santos<\/strong> (2015\/2017).<br><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5079\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-13.jpg\" alt=\"\" width=\"215\" height=\"274\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5080\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/02\/PRES-SOAMAR-14.jpg\" alt=\"\" width=\"215\" height=\"274\"><br><strong><span style=\"color: #993300;\">13<\/span> &#8211; Jobert Jos\u00e9 Salgado Filho<\/strong> (2020\/2021) &#8211; <span style=\"color: #993300;\"><strong>14<\/strong><\/span> e atual presidente &#8211; <strong>S\u00edlvio L\u00facio de Oliveira Aguiar<\/strong> (2022\/2024).<\/p>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-64","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o - Portosma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portosma.com.br\/index.php\/soamar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o - Portosma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portosma.com.br\/index.php\/soamar\/\" \/>\n<meta property=\"og:site_name\" content=\"Portosma\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T14:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"29 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portosma.com.br\/index.php\/soamar\/\",\"url\":\"https:\/\/portosma.com.br\/index.php\/soamar\/\",\"name\":\"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o - Portosma\",\"isPartOf\":{\"@id\":\"https:\/\/portosma.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portosma.com.br\/index.php\/soamar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portosma.com.br\/index.php\/soamar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg\",\"datePublished\":\"2023-01-03T23:21:44+00:00\",\"dateModified\":\"2026-06-19T14:14:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portosma.com.br\/index.php\/soamar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portosma.com.br\/index.php\/soamar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portosma.com.br\/index.php\/soamar\/#primaryimage\",\"url\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg\",\"contentUrl\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg\",\"width\":900,\"height\":494},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portosma.com.br\/index.php\/soamar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portosma.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portosma.com.br\/#website\",\"url\":\"https:\/\/portosma.com.br\/\",\"name\":\"Portosma\",\"description\":\"Um site de not\u00edcias\",\"publisher\":{\"@id\":\"https:\/\/portosma.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portosma.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portosma.com.br\/#organization\",\"name\":\"Portosma\",\"alternateName\":\"Portosma\",\"url\":\"https:\/\/portosma.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg\",\"contentUrl\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg\",\"width\":400,\"height\":115,\"caption\":\"Portosma\"},\"image\":{\"@id\":\"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o - Portosma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portosma.com.br\/index.php\/soamar\/","og_locale":"pt_BR","og_type":"article","og_title":"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o - Portosma","og_url":"https:\/\/portosma.com.br\/index.php\/soamar\/","og_site_name":"Portosma","article_modified_time":"2026-06-19T14:14:13+00:00","og_image":[{"url":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"29 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/portosma.com.br\/index.php\/soamar\/","url":"https:\/\/portosma.com.br\/index.php\/soamar\/","name":"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o - Portosma","isPartOf":{"@id":"https:\/\/portosma.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portosma.com.br\/index.php\/soamar\/#primaryimage"},"image":{"@id":"https:\/\/portosma.com.br\/index.php\/soamar\/#primaryimage"},"thumbnailUrl":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg","datePublished":"2023-01-03T23:21:44+00:00","dateModified":"2026-06-19T14:14:13+00:00","breadcrumb":{"@id":"https:\/\/portosma.com.br\/index.php\/soamar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portosma.com.br\/index.php\/soamar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portosma.com.br\/index.php\/soamar\/#primaryimage","url":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg","contentUrl":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/06\/40-ANOS-CAPA-04.jpg","width":900,"height":494},{"@type":"BreadcrumbList","@id":"https:\/\/portosma.com.br\/index.php\/soamar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portosma.com.br\/"},{"@type":"ListItem","position":2,"name":"P\u00e1gina dos Amigos da Marinha do Maranh\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/portosma.com.br\/#website","url":"https:\/\/portosma.com.br\/","name":"Portosma","description":"Um site de not\u00edcias","publisher":{"@id":"https:\/\/portosma.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portosma.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portosma.com.br\/#organization","name":"Portosma","alternateName":"Portosma","url":"https:\/\/portosma.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg","contentUrl":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg","width":400,"height":115,"caption":"Portosma"},"image":{"@id":"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":63,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages\/64\/revisions"}],"predecessor-version":[{"id":31335,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages\/64\/revisions\/31335"}],"wp:attachment":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}