{"id":218,"date":"2023-01-05T16:12:27","date_gmt":"2023-01-05T16:12:27","guid":{"rendered":"https:\/\/portosma.com.br\/?page_id=218"},"modified":"2023-01-05T16:16:01","modified_gmt":"2023-01-05T16:16:01","slug":"galerias","status":"publish","type":"page","link":"https:\/\/portosma.com.br\/index.php\/galerias\/","title":{"rendered":"GALERIAS"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"212\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-1024x576.jpg\" alt=\"\" class=\"wp-image-212\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"211\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-1-1024x768.jpg\" alt=\"\" class=\"wp-image-211\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-1-1024x768.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-1-300x225.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-1-768x576.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"500\" height=\"281\" data-id=\"207\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN08-1.jpg\" alt=\"\" class=\"wp-image-207\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN08-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN08-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"206\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN13-1.jpg\" alt=\"\" class=\"wp-image-206\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN13-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN13-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"205\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN06-1.jpg\" alt=\"\" class=\"wp-image-205\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN06-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN06-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"204\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN11-1.jpg\" alt=\"\" class=\"wp-image-204\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN11-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN11-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"530\" data-id=\"210\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN02-1.jpg\" alt=\"\" class=\"wp-image-210\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN02-1.jpg 490w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN02-1-277x300.jpg 277w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"209\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN14-1.jpg\" alt=\"\" class=\"wp-image-209\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN14-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN14-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" data-id=\"208\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03-1.jpg\" alt=\"\" class=\"wp-image-208\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03-1-300x300.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03-1-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"203\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN12-1.jpg\" alt=\"\" class=\"wp-image-203\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN12-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN12-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"202\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN07-1.jpg\" alt=\"\" class=\"wp-image-202\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN07-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN07-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"201\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN09-1.jpg\" alt=\"\" class=\"wp-image-201\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN09-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN09-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"499\" data-id=\"200\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04-1.jpg\" alt=\"\" class=\"wp-image-200\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04-1-300x300.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04-1-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"199\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN10-1.jpg\" alt=\"\" class=\"wp-image-199\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN10-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN10-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"572\" data-id=\"198\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN01-1.jpg\" alt=\"\" class=\"wp-image-198\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN01-1.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN01-1-262x300.jpg 262w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"191\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN48-1024x576.jpg\" alt=\"\" class=\"wp-image-191\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN48-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN48-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN48-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN48-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN48-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"190\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN38-1024x576.jpg\" alt=\"\" class=\"wp-image-190\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN38-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN38-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN38-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN38-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN38-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"192\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN44-1024x576.jpg\" alt=\"\" class=\"wp-image-192\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN44-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN44-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN44-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN44-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN44-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"189\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN43-1024x576.jpg\" alt=\"\" class=\"wp-image-189\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN43-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN43-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN43-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN43-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN43-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"188\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN40-1024x576.jpg\" alt=\"\" class=\"wp-image-188\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN40-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN40-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN40-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN40-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN40-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"187\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN47-1024x576.jpg\" alt=\"\" class=\"wp-image-187\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN47-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN47-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN47-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN47-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN47-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"186\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN37-1024x576.jpg\" alt=\"\" class=\"wp-image-186\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN37-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN37-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN37-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN37-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN37-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"185\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN45-1024x576.jpg\" alt=\"\" class=\"wp-image-185\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN45-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN45-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN45-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN45-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN45-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"184\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN39-1024x576.jpg\" alt=\"\" class=\"wp-image-184\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN39-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN39-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN39-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN39-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN39-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"183\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN46-1024x576.jpg\" alt=\"\" class=\"wp-image-183\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN46-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN46-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN46-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN46-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN46-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"182\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN42-1024x576.jpg\" alt=\"\" class=\"wp-image-182\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN42-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN42-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN42-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN42-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN42-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"180\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1024x576.jpg\" alt=\"\" class=\"wp-image-180\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"181\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN41-1024x576.jpg\" alt=\"\" class=\"wp-image-181\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN41-1024x576.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN41-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN41-768x432.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN41-1536x864.jpg 1536w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN41-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" data-id=\"179\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN54-1024x570.jpg\" alt=\"\" class=\"wp-image-179\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN54-1024x570.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN54-300x167.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN54-768x428.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN54-450x250.jpg 450w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN54.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1015\" height=\"478\" data-id=\"178\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN52.jpg\" alt=\"\" class=\"wp-image-178\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN52.jpg 1015w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN52-300x141.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN52-768x362.jpg 768w\" sizes=\"(max-width: 1015px) 100vw, 1015px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1015\" height=\"311\" data-id=\"177\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN21.jpg\" alt=\"\" class=\"wp-image-177\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN21.jpg 1015w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN21-300x92.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN21-768x235.jpg 768w\" sizes=\"(max-width: 1015px) 100vw, 1015px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1015\" height=\"401\" data-id=\"176\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN22.jpg\" alt=\"\" class=\"wp-image-176\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN22.jpg 1015w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN22-300x119.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN22-768x303.jpg 768w\" sizes=\"(max-width: 1015px) 100vw, 1015px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"175\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN02.jpg\" alt=\"\" class=\"wp-image-175\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"677\" data-id=\"174\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN50.jpg\" alt=\"\" class=\"wp-image-174\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN50.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN50-222x300.jpg 222w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"173\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN34.jpg\" alt=\"\" class=\"wp-image-173\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN34.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN34-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"668\" data-id=\"172\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN51.jpg\" alt=\"\" class=\"wp-image-172\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN51.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN51-225x300.jpg 225w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"170\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN36.jpg\" alt=\"\" class=\"wp-image-170\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN36.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN36-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"282\" data-id=\"169\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN33.jpg\" alt=\"\" class=\"wp-image-169\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN33.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN33-300x169.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN33-388x220.jpg 388w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"168\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN29.jpg\" alt=\"\" class=\"wp-image-168\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN29.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN29-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"167\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN35.jpg\" alt=\"\" class=\"wp-image-167\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN35.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN35-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"166\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN26.jpg\" alt=\"\" class=\"wp-image-166\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN26.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN26-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"165\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN28.jpg\" alt=\"\" class=\"wp-image-165\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN28.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN28-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"171\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-1024x768.jpg\" alt=\"\" class=\"wp-image-171\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-1024x768.jpg 1024w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-300x225.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024-768x576.jpg 768w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/IMG-20230105-WA0024.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"164\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN20.jpg\" alt=\"\" class=\"wp-image-164\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN20.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN20-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"163\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN15.jpg\" alt=\"\" class=\"wp-image-163\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN15.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN15-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"162\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN31.jpg\" alt=\"\" class=\"wp-image-162\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN31.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN31-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" data-id=\"161\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03.jpg\" alt=\"\" class=\"wp-image-161\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03-300x300.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN03-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"160\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN14.jpg\" alt=\"\" class=\"wp-image-160\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN14.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN14-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"159\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN32.jpg\" alt=\"\" class=\"wp-image-159\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN32.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN32-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"158\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN30.jpg\" alt=\"\" class=\"wp-image-158\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN30.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN30-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"157\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN27.jpg\" alt=\"\" class=\"wp-image-157\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN27.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN27-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"156\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN25.jpg\" alt=\"\" class=\"wp-image-156\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN25.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN25-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"155\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN24.jpg\" alt=\"\" class=\"wp-image-155\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN24.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN24-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"154\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN23.jpg\" alt=\"\" class=\"wp-image-154\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN23.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN23-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"148\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN11.jpg\" alt=\"\" class=\"wp-image-148\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN11.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN11-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"153\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN19.jpg\" alt=\"\" class=\"wp-image-153\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN19.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN19-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"152\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN18.jpg\" alt=\"\" class=\"wp-image-152\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN18.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN18-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"151\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN13.jpg\" alt=\"\" class=\"wp-image-151\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN13.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN13-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"150\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN17.jpg\" alt=\"\" class=\"wp-image-150\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN17.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN17-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"149\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN12.jpg\" alt=\"\" class=\"wp-image-149\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN12.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN12-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"147\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN09.jpg\" alt=\"\" class=\"wp-image-147\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN09.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN09-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"146\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN08.jpg\" alt=\"\" class=\"wp-image-146\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN08.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN08-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"145\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN07.jpg\" alt=\"\" class=\"wp-image-145\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN07.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN07-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"499\" data-id=\"144\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04.jpg\" alt=\"\" class=\"wp-image-144\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04-300x300.jpg 300w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN04-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"143\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN06.jpg\" alt=\"\" class=\"wp-image-143\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN06.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN06-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"142\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN10.jpg\" alt=\"\" class=\"wp-image-142\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN10.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN10-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" data-id=\"141\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN16.jpg\" alt=\"\" class=\"wp-image-141\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN16.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN16-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"572\" data-id=\"140\" src=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN01.jpg\" alt=\"\" class=\"wp-image-140\" srcset=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN01.jpg 500w, https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN01-262x300.jpg 262w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-218","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GALERIAS - Portosma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portosma.com.br\/index.php\/galerias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GALERIAS - Portosma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portosma.com.br\/index.php\/galerias\/\" \/>\n<meta property=\"og:site_name\" content=\"Portosma\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-05T16:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-1024x576.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portosma.com.br\/index.php\/galerias\/\",\"url\":\"https:\/\/portosma.com.br\/index.php\/galerias\/\",\"name\":\"GALERIAS - Portosma\",\"isPartOf\":{\"@id\":\"https:\/\/portosma.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portosma.com.br\/index.php\/galerias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portosma.com.br\/index.php\/galerias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-1024x576.jpg\",\"datePublished\":\"2023-01-05T16:12:27+00:00\",\"dateModified\":\"2023-01-05T16:16:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/portosma.com.br\/index.php\/galerias\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portosma.com.br\/index.php\/galerias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portosma.com.br\/index.php\/galerias\/#primaryimage\",\"url\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-scaled.jpg\",\"contentUrl\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portosma.com.br\/index.php\/galerias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portosma.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GALERIAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portosma.com.br\/#website\",\"url\":\"https:\/\/portosma.com.br\/\",\"name\":\"Portosma\",\"description\":\"Um site de not\u00edcias\",\"publisher\":{\"@id\":\"https:\/\/portosma.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portosma.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/portosma.com.br\/#organization\",\"name\":\"Portosma\",\"alternateName\":\"Portosma\",\"url\":\"https:\/\/portosma.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg\",\"contentUrl\":\"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg\",\"width\":400,\"height\":115,\"caption\":\"Portosma\"},\"image\":{\"@id\":\"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GALERIAS - Portosma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portosma.com.br\/index.php\/galerias\/","og_locale":"pt_BR","og_type":"article","og_title":"GALERIAS - Portosma","og_url":"https:\/\/portosma.com.br\/index.php\/galerias\/","og_site_name":"Portosma","article_modified_time":"2023-01-05T16:16:01+00:00","og_image":[{"url":"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-1024x576.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/portosma.com.br\/index.php\/galerias\/","url":"https:\/\/portosma.com.br\/index.php\/galerias\/","name":"GALERIAS - Portosma","isPartOf":{"@id":"https:\/\/portosma.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portosma.com.br\/index.php\/galerias\/#primaryimage"},"image":{"@id":"https:\/\/portosma.com.br\/index.php\/galerias\/#primaryimage"},"thumbnailUrl":"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-1024x576.jpg","datePublished":"2023-01-05T16:12:27+00:00","dateModified":"2023-01-05T16:16:01+00:00","breadcrumb":{"@id":"https:\/\/portosma.com.br\/index.php\/galerias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portosma.com.br\/index.php\/galerias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portosma.com.br\/index.php\/galerias\/#primaryimage","url":"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-scaled.jpg","contentUrl":"https:\/\/portosma.com.br\/wp-content\/uploads\/2023\/01\/TAMAN05-1-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/portosma.com.br\/index.php\/galerias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portosma.com.br\/"},{"@type":"ListItem","position":2,"name":"GALERIAS"}]},{"@type":"WebSite","@id":"https:\/\/portosma.com.br\/#website","url":"https:\/\/portosma.com.br\/","name":"Portosma","description":"Um site de not\u00edcias","publisher":{"@id":"https:\/\/portosma.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portosma.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/portosma.com.br\/#organization","name":"Portosma","alternateName":"Portosma","url":"https:\/\/portosma.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg","contentUrl":"https:\/\/portosma.com.br\/wp-content\/uploads\/2026\/03\/cropped-AD-PORTOSMA.jpg","width":400,"height":115,"caption":"Portosma"},"image":{"@id":"https:\/\/portosma.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=218"}],"version-history":[{"count":3,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages\/218\/revisions"}],"predecessor-version":[{"id":316,"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/pages\/218\/revisions\/316"}],"wp:attachment":[{"href":"https:\/\/portosma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}